{"id":501,"date":"2024-09-30T23:03:00","date_gmt":"2024-10-01T02:03:00","guid":{"rendered":"https:\/\/acuinor.cl\/?p=501"},"modified":"2026-05-07T12:24:36","modified_gmt":"2026-05-07T16:24:36","slug":"acuicultura-de-recirculacion-alternativa-sostenible-frente-al-cambio-climatico","status":"publish","type":"post","link":"https:\/\/acuinor.cl\/es_cl\/acuicultura-de-recirculacion-alternativa-sostenible-frente-al-cambio-climatico\/","title":{"rendered":"Potenciando una producci\u00f3n eficiente y sostenible"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"501\" class=\"elementor elementor-501\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36085a78 e-flex e-con-boxed e-con e-parent\" data-id=\"36085a78\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-10892195 e-con-full e-flex e-con e-child\" data-id=\"10892195\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3965ae9b elementor-widget elementor-widget-image\" data-id=\"3965ae9b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1683\" src=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2025\/12\/acuinor-33-scaled.jpg\" class=\"attachment-full size-full wp-image-775\" alt=\"\" srcset=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2025\/12\/acuinor-33-scaled.jpg 2560w, https:\/\/acuinor.cl\/wp-content\/uploads\/2025\/12\/acuinor-33-300x197.jpg 300w, https:\/\/acuinor.cl\/wp-content\/uploads\/2025\/12\/acuinor-33-1024x673.jpg 1024w, https:\/\/acuinor.cl\/wp-content\/uploads\/2025\/12\/acuinor-33-768x505.jpg 768w, https:\/\/acuinor.cl\/wp-content\/uploads\/2025\/12\/acuinor-33-1536x1010.jpg 1536w, https:\/\/acuinor.cl\/wp-content\/uploads\/2025\/12\/acuinor-33-2048x1346.jpg 2048w, https:\/\/acuinor.cl\/wp-content\/uploads\/2025\/12\/acuinor-33-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44fb9ed6 e-flex e-con-boxed e-con e-parent\" data-id=\"44fb9ed6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-721f2b56 elementor-widget elementor-widget-text-editor\" data-id=\"721f2b56\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 8\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>EN EL NORTE DEL PAI\u0301S, LA DIVERSIFICACIO\u0301N ACUI\u0301COLA AVANZA CON PROYECTOS DESTACADOS EN LA PRODUCCIO\u0301N DE SERIOLA Y EL DESARROLLO DEL CONGRIO COLORADO. EL PRIMERO SE ENFOCA EN LA EXPANSIO\u0301N GLOBAL Y SOSTENIBILIDAD, MIENTRAS QUE EL SEGUNDO ENFRENTA RETOS PARA MEJORAR PRA\u0301CTICAS SOSTENIBLES Y ESCALAR LA PRODUCCIO\u0301N.<\/p><div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>En los u\u0301ltimos an\u0303os, Chile ha dado pasos significativos en la diversificacio\u0301n de su industria acui\u0301cola, con una atencio\u0301n creciente hacia especies marinas como la seriola y el congrio colorado. Estos proyectos innovadores han mostrado avances significativos en te\u0301rminos de sostenibilidad y produccio\u0301n.<\/p><p>Sin embargo, para alcanzar su pleno potencial se requiere superar varios desafi\u0301os te\u0301cnicos y operativos. Las estrategias implementadas para enfrentar estos retos esta\u0301n fortaleciendo la acuicultura en el pai\u0301s.<\/p><p>Acui\u0301cola del Norte S.A. (Acuinor) es una compan\u0303i\u0301a que ha sido pionera en Chile en la produccio\u0301n de Seriola lalandi, conocida tambie\u0301n como vidriola o palometa. La empresa ha logrado establecerse mediante el cultivo en tierra utilizando sistemas de recirculacio\u0301n (RAS), marcando un hito en la industria acui\u0301cola nacional.<\/p><p>Revista AQUA conversa con Muriel Teixido\u0301, gerente Comercial y de Proyectos de la empresa, quien menciona que \u201cla produccio\u0301n de Seriola lalandi en el norte de Chile ha experimentado un desarrollo significativo desde que se iniciaron las primeras exportaciones en marzo de 2022 provenientes de las nuevas instalaciones de engorda en tierra\u201d.<\/p><p>La ejecutiva explica que Acuinor ha establecido un modelo de produccio\u0301n pionero en la regio\u0301n de Atacama, centrado en la sustentabilidad y la innovacio\u0301n tecnolo\u0301gica, con instalaciones de engorda que actualmente permiten una produccio\u0301n de alrededor de 200 toneladas anuales.<\/p><p>Agrega que hoy esta\u0301n en un proceso activo para incremen- tar la biomasa, aumentar los volu\u0301menes de produccio\u0301n, mejorar los i\u0301ndices de crecimiento de los peces e ingresar a nuevos mercados, factores claves para fortalecer su competitividad.<\/p><div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>\u201cLa evolucio\u0301n de la produccio\u0301n ha sido posible gracias a una so\u0301lida inversio\u0301n en investigacio\u0301n y desarrollo (I+D), y al apoyo fundamental de alianzas pu\u0301blico-privadas, en particular con Corfo\u201d, an\u0303ade.<\/p><p>Teixido\u0301 afirma que actualmente, Estados Unidos se po- siciona como el principal mercado para la seriola producida por Acuinor, con presencia tanto en la costa Este como en la costa Oeste.<\/p><p>\u201cEn este mercado, la seriola ha encontrado una demanda creciente, especialmente en la industria de restaurantes de sushi y establecimientos de comida asia\u0301tica, donde es apreciada por su alta calidad y sus excelentes propiedades nutricionales\u201d, asevera.<\/p><p>Asimismo, an\u0303ade que, en Europa, Italia representa un mercado significativo para Acuinor. Antes de la pandemia, desarrollaron con e\u0301xito el mercado del \u201cpan size\u201d de seriola para venta en supermercados. \u201cSi bien la pandemia nos impidio\u0301 continuar atendiendo este mercado, hoy vemos con satisfaccio\u0301n que ha tomado gran fuerza\u201d, explica.<\/p><div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>A esto se suma el mercado de los chiringuitos en Espan\u0303a, para el producto taman\u0303o plato de 600-800 y 800-1.300 gramos. \u201cEn el mercado nacional, Chile esta\u0301 mostrando un creciente intere\u0301s en la seriola, especialmente en restaurantes de alta gama que buscan productos de calidad y sustentabi- lidad\u201d, comenta.<\/p><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>\u201cEste es un mercado en desarrollo, donde vemos un gran potencial para seguir expandie\u0301ndonos tanto en el foodservice como en el retail\u201d, agrega. \u201cEn lo inmediato, estamos enfocados en expandir nuestra presencia en Sudame\u0301rica en Brasil princi- palmente -donde contamos con un importante cliente y con las certificaciones requeridas- debido a su gran colonia japonesa, que mantiene fuertes tradiciones culinarias que favorecen el consumo del producto\u201d, an\u0303ade.<\/p><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Desde Acuinor mencionan que creen que Brasil tiene un tremendo potencial y sera\u0301 un mercado crucial para su crecimiento en la regio\u0301n, donde cuentan con ventajas de transporte para el producto fresco refrigerado. Adema\u0301s, explican que ven un gran potencial en otros mercados sudamericanos como Colombia.<\/p><p>Mirando hacia el futuro, \u201cestamos explorando activamente nuevos mercados de alto potencial, entre ellos, destacamos a Emiratos A\u0301rabes Unidos, Singapur, China (producto congelado principalmente), Hong Kong, Me\u0301xico, Francia, Alemania y el Reino Unido, adema\u0301s de Espan\u0303a e Italia, todos ellos con un creciente intere\u0301s en productos del mar de alta calidad\u201d.<\/p><p>\u201cNuestra estrategia incluye una expansio\u0301n integral que abarca la participacio\u0301n en misiones comerciales, la asistencia a ferias internacionales, y la realizacio\u0301n de estudios de mercado para una ma\u0301s a\u0301gil y eficiente penetracio\u0301n de mercados\u201d, considera.<\/p><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>PERSPECTIVAS EN EL MERCADO<\/p><p>Desde Acuinor, Muriel explica que las perspectivas del mercado norteamericano para la seriola son muy prometedoras. \u201cEn Estados Unidos, el consumo de productos del mar ha venido en aumento, impulsado por una creciente conciencia sobre los beneficios para la salud y la sostenibilidad ambiental de las fuentes de protei\u0301nas marinas\u201d.<\/p><p>En este contexto, agrega que la seriola ha logrado consolidarse como una gran opcio\u0301n en restaurantes de sushi y comida asia\u0301tica a lo largo de las costas Este y Oeste, donde es apreciada por su textura firme, su sabor delicado, sus excepcionales propiedades nutricionales, como su alto contenido de omega-3 y protei\u0301nas, por ser libres de para\u0301sitos y antibio\u0301ticos. \u201cA futuro, Acuinor tiene como principal objetivo escalar su produccio\u0301n para alcanzar volu\u0301menes que permitan la rentabilidad y competitividad necesarias para consolidarse como li\u0301deren la produccio\u0301n de esta especie\u201d, comenta.<\/p><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>En lo inmediato, la ejecutiva an\u0303ade que todos los esfuerzos esta\u0301n centrados en lograr un primer escalamiento productivo, que les permita incrementar su capacidad de produccio\u0301n actual hasta volu\u0301menes cercanos a las 600 toneladas anuales.<\/p><p>\u201cEste paso es crucial no solo para aumentar el volumen de nuestra oferta sino tambie\u0301n para generar economi\u0301as y eficiencias productivas. Este primer escalamiento permitira\u0301 afianzar la estabilidad financiera de la compan\u0303i\u0301a, brinda\u0301ndonos ma\u0301rgenes ma\u0301s competitivos en el mercado global\u201d, afirma.<\/p><p>Menciona, adema\u0301s, que a partir de este punto el potencial para crecer es muy interesante, esto considerando que la produccio\u0301n anual es cercana a las 180.000 toneladas, que existe actualmente demanda insatisfecha y nuevos mercados donde crecer.<\/p><p>\u201cParalelamente, continuaremos enfoca\u0301ndonos en la expansio\u0301n de nuestra presencia en los mercados internacionales, explorando y desarrollando nuevos destinos de exportacio\u0301n en diferentes formatos\u201d, concluye.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>EN EL NORTE DEL PAI\u0301S, LA DIVERSIFICACIO\u0301N ACUI\u0301COLA AVANZA CON PROYECTOS DESTACADOS EN LA PRODUCCIO\u0301N DE SERIOLA Y EL DESARROLLO DEL CONGRIO COLORADO. EL PRIMERO SE ENFOCA EN LA EXPANSIO\u0301N GLOBAL Y SOSTENIBILIDAD, MIENTRAS QUE EL SEGUNDO ENFRENTA RETOS PARA MEJORAR PRA\u0301CTICAS SOSTENIBLES Y ESCALAR LA PRODUCCIO\u0301N. En los u\u0301ltimos an\u0303os, Chile ha dado pasos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":775,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa"],"_links":{"self":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":11,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"predecessor-version":[{"id":1253,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/501\/revisions\/1253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/media\/775"}],"wp:attachment":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}