{"id":2146,"date":"2017-07-05T17:03:00","date_gmt":"2017-07-05T21:03:00","guid":{"rendered":"https:\/\/acuinor.cl\/?p=2146"},"modified":"2026-05-08T17:05:44","modified_gmt":"2026-05-08T21:05:44","slug":"ficha-tecnica-seriola-lalandi","status":"publish","type":"post","link":"https:\/\/acuinor.cl\/es_cl\/ficha-tecnica-seriola-lalandi\/","title":{"rendered":"Ficha T\u00e9cnica: Seriola lalandi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2146\" class=\"elementor elementor-2146\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d312933 e-flex e-con-boxed e-con e-parent\" data-id=\"2d312933\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4649d7f0 e-con-full e-flex e-con e-child\" data-id=\"4649d7f0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21b83aaa elementor-widget elementor-widget-image\" data-id=\"21b83aaa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"882\" height=\"569\" src=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/05\/Captura-de-Pantalla-2026-05-08-a-las-16.36.08.png\" class=\"attachment-full size-full wp-image-2148\" alt=\"\" srcset=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/05\/Captura-de-Pantalla-2026-05-08-a-las-16.36.08.png 882w, https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/05\/Captura-de-Pantalla-2026-05-08-a-las-16.36.08-300x194.png 300w, https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/05\/Captura-de-Pantalla-2026-05-08-a-las-16.36.08-768x495.png 768w, https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/05\/Captura-de-Pantalla-2026-05-08-a-las-16.36.08-18x12.png 18w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-770b0703 e-flex e-con-boxed e-con e-parent\" data-id=\"770b0703\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e99a3f elementor-widget elementor-widget-text-editor\" data-id=\"9e99a3f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 1\"><p data-start=\"151\" data-end=\"243\"><strong data-start=\"151\" data-end=\"177\">Otros nombres comunes:<\/strong> Palometa, Dorado, Vidriola, Toremo, Hiramasa, Yellowtail Kingfish<\/p><p data-start=\"245\" data-end=\"533\">Es un pez pel\u00e1gico de la familia Carangidae, posee cuerpo fusiforme, alargado y levemente comprimido. Las aletas pectorales se encuentra casi a la misma altura que la aleta p\u00e9lvica. El sistema digestivo y musculatura evidencia su comportamiento de pez pel\u00e1gico carn\u00edvoro y nataci\u00f3n veloz.<\/p><p data-start=\"535\" data-end=\"555\"><strong data-start=\"535\" data-end=\"555\">Fuente: Acuinor.<\/strong><\/p><h2 data-section-id=\"1e5x7br\" data-start=\"557\" data-end=\"575\">H\u00e1bitat natural<\/h2><p data-start=\"577\" data-end=\"1044\">Es una especie migratoria, que avanza a trav\u00e9s del oc\u00e9ano \u00cdndico, Atl\u00e1ntico y Pac\u00edfico. En Chile se encuentra principalmente al norte de Chile entre la II y IV regi\u00f3n, donde se concentra su pesca; adem\u00e1s del archipi\u00e9lago de Juan Fern\u00e1ndez, mayoritariamente en los meses estivales. Habita en aguas templadas (18-24\u00b0C), tanto pel\u00e1gicas como demersales, en un rango que var\u00eda entre los 3 y 825 metros de profundidad, aunque tambi\u00e9n pueden encontrarse en aguas m\u00e1s fr\u00edas.<\/p><h2 data-section-id=\"wtis6o\" data-start=\"1046\" data-end=\"1084\">Instalaciones de cultivo requeridas<\/h2><p data-start=\"1086\" data-end=\"1204\">La experiencia ha demostrado la factibilidad t\u00e9cnica de su cultivo bajo sistema de recirculaci\u00f3n (RAS) consistente en:<\/p><ul data-start=\"1206\" data-end=\"1712\"><li data-section-id=\"1hjzhz1\" data-start=\"1206\" data-end=\"1272\">Hatchery con 4 salas de reproductores independientes entre s\u00ed.<\/li><li data-section-id=\"rh71hj\" data-start=\"1273\" data-end=\"1300\">Una sala de incubaci\u00f3n.<\/li><li data-section-id=\"159nk91\" data-start=\"1301\" data-end=\"1508\">Unidades para la producci\u00f3n de alimentos vivos, microalgas (cepario, intermedio y masivo); rot\u00edferos (con sistemas de recirculaci\u00f3n, batch y flujo continuo) y artemias con sistema magnetizado de quistes.<\/li><li data-section-id=\"167m1ng\" data-start=\"1509\" data-end=\"1624\">Sistemas para la producci\u00f3n de larvas de peces marinos tanto en sistema de flujo abierto como en recirculaci\u00f3n.<\/li><li data-section-id=\"1hxsdgs\" data-start=\"1625\" data-end=\"1671\">Sistema de recirculaci\u00f3n para pre-engorda.<\/li><li data-section-id=\"wf3152\" data-start=\"1672\" data-end=\"1712\">Sistema de recirculaci\u00f3n para engorda.<\/li><\/ul><h2 data-section-id=\"1xgyu05\" data-start=\"1714\" data-end=\"1729\">Alimentaci\u00f3n<\/h2><p data-start=\"1731\" data-end=\"1774\">Se alimenta de peque\u00f1os peces y crust\u00e1ceos.<\/p><h2 data-section-id=\"1ptpake\" data-start=\"129\" data-end=\"159\">Organizaciones involucradas<\/h2><p data-start=\"161\" data-end=\"397\">Acu\u00edcola del Norte y Corfo: Beneficiarios del proyecto.<br data-start=\"216\" data-end=\"219\" \/>Organizaciones de apoyo: Universidad de Chile-Laboratorio Favet Inbiogen, ADL Diagnostic, Universidad de Concepci\u00f3n, Fundaci\u00f3n Chile, Ecosea Farming, Apta Aqua y Skretting Chile.<\/p><h2 data-section-id=\"dn14u0\" data-start=\"399\" data-end=\"437\">Nivel de avance en ciclo productivo<\/h2><p data-start=\"439\" data-end=\"876\">Acu\u00edcola del Norte cuenta con un plantel de reproductores de 150 ejemplares acondicionados termofotoperi\u00f3dicamente, los que otorgan desoves continuos que permiten continuar el ciclo productivo pasando por la incubaci\u00f3n de huevos, primera alimentaci\u00f3n (alimentos vivos), destete, pre engorda de juveniles y posterior engorda, hasta cerrar el ciclo productivo con la obtenci\u00f3n de producto procesado terminado fresco todos los d\u00edas del a\u00f1o.<\/p><h2 data-section-id=\"1x96g1u\" data-start=\"878\" data-end=\"893\">Fechas clave<\/h2><p data-start=\"895\" data-end=\"911\">Sin informaci\u00f3n.<\/p><h2 data-section-id=\"1kap8pb\" data-start=\"913\" data-end=\"942\">Volumen de producci\u00f3n 2016<\/h2><p data-start=\"944\" data-end=\"1470\">A la fecha, se est\u00e1 exportando producto fresco entero eviscerado, entre 800 gramos y un kilo y medio a distintos destinos (400 kilos a la semana), con la finalidad de desarrollar diferentes pruebas de mercado. Tambi\u00e9n se cuenta con una producci\u00f3n de juveniles estable y continua, y una producci\u00f3n de 20 ton al a\u00f1o en sistema de recirculaci\u00f3n con continuidad semanal en la entrega del producto. Se dar\u00e1 comienzo en los pr\u00f3ximos meses a la construcci\u00f3n de engorda comercial con sistema de recirculaci\u00f3n para 650-1.000 toneladas.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Otros nombres comunes: Palometa, Dorado, Vidriola, Toremo, Hiramasa, Yellowtail Kingfish Es un pez pel\u00e1gico de la familia Carangidae, posee cuerpo fusiforme, alargado y levemente comprimido. Las aletas pectorales se encuentra casi a la misma altura que la aleta p\u00e9lvica. El sistema digestivo y musculatura evidencia su comportamiento de pez pel\u00e1gico carn\u00edvoro y nataci\u00f3n veloz. Fuente: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2148,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa"],"_links":{"self":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/2146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/comments?post=2146"}],"version-history":[{"count":6,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/2146\/revisions"}],"predecessor-version":[{"id":2153,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/2146\/revisions\/2153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/media\/2148"}],"wp:attachment":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/media?parent=2146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/categories?post=2146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/tags?post=2146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}