{"id":1285,"date":"2022-11-02T12:36:00","date_gmt":"2022-11-02T15:36:00","guid":{"rendered":"https:\/\/acuinor.cl\/?p=1285"},"modified":"2026-05-07T12:24:36","modified_gmt":"2026-05-07T16:24:36","slug":"planta-de-engorda-de-seriola-busca-una-produccion-anual-de-150-a-200-toneladas-al-ano","status":"publish","type":"post","link":"https:\/\/acuinor.cl\/es_cl\/planta-de-engorda-de-seriola-busca-una-produccion-anual-de-150-a-200-toneladas-al-ano\/","title":{"rendered":"Planta de engorda de seriola busca una producci\u00f3n anual de 150 a 200 toneladas al a\u00f1o"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1285\" class=\"elementor elementor-1285\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46d8966f e-flex e-con-boxed e-con e-parent\" data-id=\"46d8966f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6f312234 e-con-full e-flex e-con e-child\" data-id=\"6f312234\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a6228fc elementor-widget elementor-widget-image\" data-id=\"1a6228fc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1088\" height=\"760\" src=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/04\/Captura-de-Pantalla-2026-04-28-a-las-12.12.18.png\" class=\"attachment-full size-full wp-image-1286\" alt=\"\" srcset=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/04\/Captura-de-Pantalla-2026-04-28-a-las-12.12.18.png 1088w, https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/04\/Captura-de-Pantalla-2026-04-28-a-las-12.12.18-300x210.png 300w, https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/04\/Captura-de-Pantalla-2026-04-28-a-las-12.12.18-1024x715.png 1024w, https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/04\/Captura-de-Pantalla-2026-04-28-a-las-12.12.18-768x536.png 768w, https:\/\/acuinor.cl\/wp-content\/uploads\/2026\/04\/Captura-de-Pantalla-2026-04-28-a-las-12.12.18-18x12.png 18w\" sizes=\"(max-width: 1088px) 100vw, 1088px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6438205 e-flex e-con-boxed e-con e-parent\" data-id=\"6438205\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-441797f4 elementor-widget elementor-widget-text-editor\" data-id=\"441797f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"372\" data-end=\"476\"><strong data-start=\"372\" data-end=\"476\">DE PRODUCTO TERMINADO. En Caldera se inaugur\u00f3 recinto \u00fanico en Chile y con tecnolog\u00eda 100% nacional.<\/strong><\/p><p data-start=\"478\" data-end=\"518\"><strong data-start=\"478\" data-end=\"518\">Redacci\u00f3n<br data-start=\"489\" data-end=\"492\" \/><a class=\"decorated-link cursor-pointer\" rel=\"noopener\" data-start=\"492\" data-end=\"516\">cronica@diarioatacama.cl<\/a><\/strong><\/p><p data-start=\"520\" data-end=\"966\">Con la presencia de diversas autoridades comunales, gerentes de Corfo a nivel nacional, proveedores y directores, se realiz\u00f3 la inauguraci\u00f3n de la planta de engorda de la especie marina Caldera. Esta es la primera planta dise\u00f1ada para la producci\u00f3n y engorda de Seriola Lalandi en cautiverio, adem\u00e1s, con un moderno sistema de cultivo en tierra con recirculaci\u00f3n, RAS, en el cual se implement\u00f3 de primer nivel para su implementaci\u00f3n y desarrollo.<\/p><p data-start=\"968\" data-end=\"1316\">El proyecto forma parte de las acciones contempladas por el Programa Tecnol\u00f3gico Estrat\u00e9gico de Seriola, apoyado por Corfo, que busca crear una industria de esta especie en Chile, al demostrar las potencialidades introduciendo tecnolog\u00edas de engorda \u201cde bajo costo\u201d en operaci\u00f3n, con resultados productivos y econ\u00f3micos competitivos y sustentables.<\/p><p data-start=\"1318\" data-end=\"1654\">Lograr la diversificaci\u00f3n acu\u00edcola en Chile, a trav\u00e9s de nuevas especies con alto potencial aprovechando la matriz productiva generada por la industria salmonera permiti\u00f3, entre otros casos, reducir la dependencia de un solo componente y generar mayor tecnolog\u00eda productiva en nuestras regiones para poder transferirla a otros sectores.<\/p><p data-start=\"1656\" data-end=\"1854\">En este sentido, la Seriola Lalandi de mayor crecimiento y de alto valor en mercado asi\u00e1tico y nacional, puede ser criada y reproducida en cautiverio, robusteciendo su producci\u00f3n y comercializaci\u00f3n.<\/p><p data-start=\"1856\" data-end=\"1969\">El gerente general de Acuinor, <strong data-start=\"1887\" data-end=\"1904\">Pablo Segovia<\/strong>, destac\u00f3 la importancia de la innovaci\u00f3n y del trabajo conjunto.<\/p><p data-start=\"1971\" data-end=\"2250\">Asimismo, se indic\u00f3 que \u201cgracias a la implementaci\u00f3n de la tecnolog\u00eda en un sistema de recirculaci\u00f3n que fue desarrollado con tecnolog\u00eda nacional, donde los equipos fueron adaptados a proveedores locales, hoy podemos decir que esta es la primera instalaci\u00f3n de engorda de peces&#8230;<\/p><p data-start=\"509\" data-end=\"851\">Agreg\u00f3 que \u201clo que hay principalmente es una red para producir para la fase de agua dulce con sistema de recirculaci\u00f3n, principalmente, tecnolog\u00eda en tierra y all\u00ed se logr\u00f3 m\u00e1s o menos a talla de 500 gramos, casi base del ciclo completo en tierra, desde reproductores, desove, la fase primera de alimentaci\u00f3n, nursery, pre-engorda y engorda\u201d.<\/p><p data-start=\"853\" data-end=\"1368\">Por su parte, el Gobernador de la Regi\u00f3n de Atacama, <strong data-start=\"906\" data-end=\"923\">Miguel Vargas<\/strong>, presente en la actividad, se\u00f1al\u00f3 que \u201cesperemos dijo que Atacama no puede seguir dependiendo de una actividad econ\u00f3mica, tenemos que apostar con decisi\u00f3n, hacia un proceso mayor de diversificaci\u00f3n de nuestra econom\u00eda y as\u00ed aparece con mucha fuerza la acuicultura, por eso que este proyecto es ejemplar, es una especie de que no depende importaci\u00f3n de tecnolog\u00eda, donde el Ministerio de Econom\u00eda permite iniciar una industria que agrega valor\u201d.<\/p><hr data-start=\"1370\" data-end=\"1373\" \/><h2 data-section-id=\"laf4qw\" data-start=\"1375\" data-end=\"1396\">LO QUE SE PRETENDE<\/h2><p data-start=\"1398\" data-end=\"1582\">Con la planta de engorda y en operaci\u00f3n bajo un modelo de producci\u00f3n continuo con cosechas semanales y disponibilidad todo el a\u00f1o para el mercado nacional e internacional, se pretende:<\/p><ul data-start=\"1584\" data-end=\"2430\"><li data-section-id=\"x5cmrn\" data-start=\"1584\" data-end=\"1698\">Atraer nuevos participantes para la asociaci\u00f3n e iniciaci\u00f3n de la industria de Seriola en zona norte de Chile.<\/li><li data-section-id=\"1nv1va1\" data-start=\"1699\" data-end=\"1901\">Desarrollar material gen\u00e9tico nacional en producto en el norte del pa\u00eds mediante la generaci\u00f3n en el tiempo de proveedores de bienes y servicios, as\u00ed como la generaci\u00f3n de empleo asociado al sector.<\/li><li data-section-id=\"pxvm40\" data-start=\"1902\" data-end=\"2006\">Lograr en un corto plazo la producci\u00f3n a nivel industrial de esta nueva especie acu\u00edcola para Chile.<\/li><li data-section-id=\"q4mj7\" data-start=\"2007\" data-end=\"2210\">Priorizar la eficiencia, competitividad e innovaci\u00f3n mediante el uso de tecnolog\u00edas de frontera para una producci\u00f3n sustentable y acorde con nuevas exigencias respecto de impacto social y desarrollo.<\/li><li data-section-id=\"hewlm4\" data-start=\"2211\" data-end=\"2430\">Proporcionar un alimento saludable, de calidad superior, con alto contenido de prote\u00ednas y \u00e1cidos grasos omega 3 que contribuyan al suministro de la demanda alimentaria frente a la necesidad creciente de la poblaci\u00f3n.<\/li><\/ul><hr data-start=\"2432\" data-end=\"2435\" \/><p data-start=\"2437\" data-end=\"2545\">La empresa <strong data-start=\"2448\" data-end=\"2459\">Acuinor<\/strong>, ubicada en Caldera, realiz\u00f3 una visita guiada a autoridades, clientes y proveedores.<\/p><hr data-start=\"2547\" data-end=\"2550\" \/><p data-start=\"2552\" data-end=\"2953\">Las autoridades tambi\u00e9n destacaron que \u201clos programas tecnol\u00f3gicos que buscan el desarrollo de nuevas cadenas, como en este caso la capacidad de alto aprovechamiento, ayudan a crecer nuevas actividades econ\u00f3micas en la regi\u00f3n. Hoy vemos una planta concreta, pero eso parti\u00f3 hace 8 a\u00f1os, cuando naci\u00f3 la idea, luego tuvimos que dar una apuesta desde el Estado de largo plazo, impulsar esta tecnolog\u00eda\u201d.<\/p><hr data-start=\"2955\" data-end=\"2958\" \/><p data-start=\"2960\" data-end=\"3331\"><strong data-start=\"2960\" data-end=\"2977\">Pablo Segovia<\/strong> indic\u00f3 que \u201cla recirculaci\u00f3n, lo que hicimos ac\u00e1 es que se necesitaba tecnolog\u00eda en Chile para engordar peces y desarrollamos con tecnolog\u00eda nacional, donde los equipos fueron adaptados a proveedores locales. Hoy podemos decir que esta es la primera planta de cultivo de peces en recirculaci\u00f3n con una producci\u00f3n sustentable con lo que producimos aqu\u00ed\u201d.<\/p><hr data-start=\"3333\" data-end=\"3336\" \/><p data-start=\"3338\" data-end=\"3502\">Desde el inicio en 2007, Acu\u00edcola del Norte S.A. viene trabajando junto a Fundaci\u00f3n Chile y organismos del Estado para construir una nueva industria para la regi\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DE PRODUCTO TERMINADO. En Caldera se inaugur\u00f3 recinto \u00fanico en Chile y con tecnolog\u00eda 100% nacional. Redacci\u00f3ncronica@diarioatacama.cl Con la presencia de diversas autoridades comunales, gerentes de Corfo a nivel nacional, proveedores y directores, se realiz\u00f3 la inauguraci\u00f3n de la planta de engorda de la especie marina Caldera. Esta es la primera planta dise\u00f1ada para la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1286,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa"],"_links":{"self":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/1285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/comments?post=1285"}],"version-history":[{"count":3,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/1285\/revisions"}],"predecessor-version":[{"id":1289,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/posts\/1285\/revisions\/1289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/media\/1286"}],"wp:attachment":[{"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/media?parent=1285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/categories?post=1285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acuinor.cl\/es_cl\/wp-json\/wp\/v2\/tags?post=1285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}