{"id":2088,"date":"2022-06-13T12:25:00","date_gmt":"2022-06-13T16:25:00","guid":{"rendered":"https:\/\/acuinor.cl\/?p=2088"},"modified":"2026-05-08T14:51:44","modified_gmt":"2026-05-08T18:51:44","slug":"muriel-teixido-la-produccion-de-seriola-chilena-ya-comenzo-y-junto-a-esto-el-surgimiento-de-una-nueva-industria","status":"publish","type":"post","link":"https:\/\/acuinor.cl\/en\/muriel-teixido-la-produccion-de-seriola-chilena-ya-comenzo-y-junto-a-esto-el-surgimiento-de-una-nueva-industria\/","title":{"rendered":"Muriel Teixid\u00f3: \u201cLa producci\u00f3n de Seriola chilena ya comenz\u00f3 y junto a esto el surgimiento de una nueva industria\u201d"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2088\" class=\"elementor elementor-2088\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23d42ee5 e-flex e-con-boxed e-con e-parent\" data-id=\"23d42ee5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2ff59bf7 e-con-full e-flex e-con e-child\" data-id=\"2ff59bf7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b9e7309 elementor-widget elementor-widget-image\" data-id=\"5b9e7309\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"712\" height=\"628\" src=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2022\/06\/Captura-de-Pantalla-2026-05-08-a-las-14.49.53.png\" class=\"attachment-full size-full wp-image-2106\" alt=\"\" srcset=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2022\/06\/Captura-de-Pantalla-2026-05-08-a-las-14.49.53.png 712w, https:\/\/acuinor.cl\/wp-content\/uploads\/2022\/06\/Captura-de-Pantalla-2026-05-08-a-las-14.49.53-300x265.png 300w, https:\/\/acuinor.cl\/wp-content\/uploads\/2022\/06\/Captura-de-Pantalla-2026-05-08-a-las-14.49.53-14x12.png 14w\" sizes=\"(max-width: 712px) 100vw, 712px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5dbc302c e-flex e-con-boxed e-con e-parent\" data-id=\"5dbc302c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36694edd elementor-widget elementor-widget-text-editor\" data-id=\"36694edd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\"><time>Jun 13, 2022<\/time><\/span><\/p><p>La gerente Comercial y Proyectos de Acuinor, convers\u00f3 con AQUA sobre el estado actual de la producci\u00f3n de la Seriola en el norte de nuestro pa\u00eds.<\/p><p>Ya son m\u00e1s de 15 a\u00f1os que comenz\u00f3 en Chile la producci\u00f3n de Seriola lalandi (o tambi\u00e9n llamado yellowtail, hiramasa o palometa), y desde entonces ha obtenido importantes avances, tanto en materia t\u00e9cnica, gen\u00e9tica, \u00a0y ahora comercial, puesto en marzo se cumpli\u00f3 el gran hito de comenzar las primeras exportaciones<\/p><p>En conversaci\u00f3n con Medios AQUA, la gerente comercial y de proyectos de Acuinor, Muriel Teixid\u00f3, comenta respecto de la situaci\u00f3n del cultivo de Seriola hoy, las exportaciones del recurso, los nuevos mercados a los que est\u00e1n enfocando y las expectativas a futuro.<\/p><p><strong>\u00bfEn qu\u00e9 se encuentra hoy la producci\u00f3n de Seriola lalandi?<\/strong><\/p><p>Podemos afirmar que la producci\u00f3n de Seriola chilena ya comenz\u00f3 y junto a esto el surgimiento de una nueva industria en la regi\u00f3n de Atacama. Hoy en d\u00eda, las nuevas instalaciones de engorda, ya finalizadas, se encuentran en operaci\u00f3n y funcionamiento y han comenzado las cosechas semanales que est\u00e1n siendo exportadas a dos clientes, uno en Europa y otro en Estados Unidos.<\/p><p>Si bien los vol\u00famenes exportados son peque\u00f1os, 400 Kg a la semana, puesto que reci\u00e9n estamos partiendo (desde fines de marzo), esperamos poder ir aument\u00e1ndolos paulatinamente hasta alcanzar el m\u00e1ximum standing stock en donde las cosechas semanales bordear\u00e1n las 3,6 toneladas. As\u00ed mismo el peso promedio actual de cosecha es de 3 kg, tama\u00f1o que ir\u00e1 progresivamente en aumento hasta alcanzar los 5 kg peso promedio de cosecha que es nuestro objetivo.<\/p><p><strong>Las exportaciones de Seriola partieron en marzo de este a\u00f1o. Nos puedes contar \u00bfc\u00f3mo se gest\u00f3 la b\u00fasqueda de clientes, y c\u00f3mo han sido estos primeros meses de exportaci\u00f3n del recurso, considerando que la pandemia aun no finaliza del todo?<\/strong><\/p><p>Desde el inicio, el mercado siempre ha sido un tema primordial para Acuinor, tanto as\u00ed que como parte de uno de los programas Corfo se realizaron 4 estudios de mercado \u2013 USA, Brasil, Asia y Europa \u2013 donde se contactaron potenciales clientes, se enviaron muestras, se realizaron algunos focus group y se obtuvo importante retroalimentaci\u00f3n.<\/p><p>Nos hemos preocupado permanentemente adem\u00e1s, de participar de misiones comerciales, asistir a las principales ferias y encuentros del sector y as\u00ed poder estar presentes en los mercados de inter\u00e9s para entablar relaciones comerciales, hacer los contactos y obtener informaci\u00f3n actualizada de mercado de primera fuente. En todo esto, ProChile ha jugado un importante rol al apoyar parte de estas actividades.<\/p><p>Es importante se\u00f1alar que este pez es conocido y muy bien aceptado internacionalmente y si bien su mercado a\u00fan es incipiente, cuenta con un gran potencial de desarrollo por las caracter\u00edsticas del pez, su carne blanca, textura firme, su versatilidad en la cocina, es altamente apreciado por chefs por sus caracter\u00edsticas culinarias, por sus propiedades nutricionales, alto contenido de prote\u00ednas y omega 3.<\/p><p>En el transcurso de estos primeros meses de exportaciones, en t\u00e9rminos log\u00edsticos no hemos tenido inconvenientes, nuestra carga que es fresco sale v\u00eda a\u00e9rea desde Copiap\u00f3 a Santiago y luego contin\u00faa con el tramo internacional hasta destino. Contamos con oferta diaria de vuelos tanto dom\u00e9sticos como internacionales.<\/p><p>En cuanto a la demanda, notamos que esta ha aumentado, gatillado principalmente por una limitada oferta de Seriolas, por la reactivaci\u00f3n del <em>food service<\/em> y tambi\u00e9n por un aumento del consumo de esta especie. Esperamos que esta tendencia se mantenga durante un tiempo y que a futuro exista una mayor oferta, que d\u00e9 a conocer m\u00e1s este producto y gatille una mayor demanda.<\/p><p><strong>En una entrevista con nuestro medio mencion\u00f3 que los principales mercados para la Seriola eran los europeos, y que ve\u00edan la posibilidad de sumar China a futuro. \u00bfEsos planes se mantienen?, \u00bfHa cambiado?<\/strong><\/p><p>Nuestro primer foco hoy en d\u00eda es Estados Unidos y Europa, ambos mercados con una alta y creciente demanda, y precisamente a donde estamos exportando desde fines de marzo. En la medida que el volumen de cosechas semanales aumente, podremos atender a nuevos clientes y sumar nuevos mercados como lo es Brasil, donde existe un potencial tremendo, dada la gran poblaci\u00f3n asi\u00e1tica que tiene, y mirar tambi\u00e9n a alg\u00fan otro mercado dentro de Am\u00e9rica.<\/p><p>Sin duda China siempre ha estado en nuestra mira y lo estamos prospectando a trav\u00e9s de algunas actividades con ProChile, sin embargo sabemos que requerir\u00e1 de mayor volumen que a\u00fan no tenemos disponible.<\/p><p><strong>En el mercado norteamericano ha habido una explosi\u00f3n en el consumo de seafood. \u00bfC\u00f3mo cree que son las perspectivas de ese mercado para la seriola?<\/strong><\/p><p>Efectivamente, el consumo de seafood ha venido en aumento en el mercado norteamericano. Esto se explica en parte por el aumento de su consumo entre los consumidores frecuentes, el aumento de compradores que cocinan o se atreven a preparar los productos del mar en casa (gatillado por el cierre de restaurantes) y al aumento de compradores que los eligen por su calidad nutricional o por razones de sostenibilidad.<\/p><p>Aqu\u00ed encaja muy bien la Seriola, sabemos que es un producto de calidad superior con alto contenido de prote\u00ednas, rico en \u00e1cidos grasos omega 3 y que adem\u00e1s, en el caso de Acuinor, se produce en sistemas de cultivo sustentables, ecol\u00f3gicos y de bajas emisiones de CO2.<\/p><p>Las perspectivas son buenas\u2026, si bien la Seriola en Estados Unidos (principalmente <em>Seriola quinqueradiata<\/em> o Hamachi proveniente de Jap\u00f3n y <em>Seriola rivoliana<\/em> o Kampachi proveniente de Hawaii y el Golfo de M\u00e9xico) se encuentra presente en gran parte de los restaurantes de sushi y restaurantes de comida asi\u00e1tica a lo largo de la costa este y oeste, hay un tremendo potencial tanto para el <em>food service<\/em>como para el <em>retail<\/em>.<\/p><p>Por su calidad y sustentabilidad\u00a0poco a poco est\u00e1n conquistando el mercado y desplazando preferencias.<\/p><p><strong>\u00bfC\u00f3mo ve el cultivo de la seriola en el norte del pa\u00eds? \u00bfCree que haya perspectivas de poder seguir expandi\u00e9ndose y formar una nueva industria?<\/strong><\/p><p>Sin duda, esta es un industria naciente que ya parti\u00f3, en la medida que este y otros proyectos est\u00e9n en funcionamiento, se ir\u00e1n sumando nuevos actores, se generar\u00e1 una red de trabajo transversal y se desarrollar\u00e1n m\u00e1s y nuevos proveedores de bienes y servicios creando encadenamientos productivos que fortalecer\u00e1n las cadenas de valor en el norte del pa\u00eds. Esto ser\u00e1 fundamental para la competitividad de esta industria.<\/p><p><strong>\u00bfC\u00f3mo ha sido el apoyo de Corfo a trav\u00e9s del Programa Tecnol\u00f3gico Estrat\u00e9gico?<\/strong><\/p><p>El apoyo de Corfo ha sido fundamental para llegar a donde se est\u00e1 hoy en d\u00eda en materia de desarrollo tecnol\u00f3gico y productivo y ya con una industria en surgimiento. Para esto, Acuinor viene trabajando con la instituci\u00f3n desde 2007 en una serie de proyectos y dos grandes iniciativas como lo fue el PDAC y como lo es el PTEC \u2013 Programa Tecnol\u00f3gico Estrat\u00e9gico \u2013 que a\u00fan est\u00e1 en desarrollo. Insisto que los proyectos de esta envergadura y de largo aliento, m\u00e1s a\u00fan cuando se trata de desarrollar una nueva especie, no son factibles de llevarse a cabo sin una cooperaci\u00f3n p\u00fablico-privada, el apoyo de Corfo valida este tipo de iniciativas, les da credibilidad y les facilita el acceso a nuevas fuentes de financiamiento.<\/p><p>Quisiera destacar adem\u00e1s el trabajo de Corfo como nexo con instituciones como Sernapesca, Subpesca y Subsecretar\u00eda para las Fuerza Armadas, sin duda la diversificaci\u00f3n acu\u00edcola presenta tambi\u00e9n grandes desaf\u00edos en materia normativa. Para esto Corfo mantiene convenios de colaboraci\u00f3n con estas entidades lo que ha resultado de gran apoyo frente a problem\u00e1ticas propias de cultivar una nueva especie.<\/p><p><strong>\u00bfQu\u00e9 etapas son las que se vienen a futuro para la producci\u00f3n de la seriola?, \u00bfCu\u00e1les son las proyecciones a futuro de Acuinor?<\/strong><\/p><p>Sin lugar a dudas, lo que viene es escalar la producci\u00f3n a nivel de empresa para alcanzar vol\u00famenes rentables que logren competitividad y crecimiento. Este es un negocio de escala.<\/p><p>Las instalaciones de engorda actuales nos permitir\u00e1n producir 200 ton de biomasa de Seriola al a\u00f1o. La siguiente fase ser\u00e1 aumentarla a 600 ton para luego incrementarla a unas 1.000 o 2.000 toneladas.<\/p><p>En materia comercial estamos trabajando la estrategia de marca, que tendr\u00e1 una nueva identidad visual y <em>tagline<\/em> para lograr el posicionamiento que queremos para nuestro producto. Esto, en l\u00ednea adem\u00e1s con el desarrollo de productos con valor agregado que comenzaremos a trabajar desde ya.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Jun 13, 2022 La gerente Comercial y Proyectos de Acuinor, convers\u00f3 con AQUA sobre el estado actual de la producci\u00f3n de la Seriola en el norte de nuestro pa\u00eds. Ya son m\u00e1s de 15 a\u00f1os que comenz\u00f3 en Chile la producci\u00f3n de Seriola lalandi (o tambi\u00e9n llamado yellowtail, hiramasa o palometa), y desde entonces ha [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa"],"_links":{"self":[{"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/posts\/2088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/comments?post=2088"}],"version-history":[{"count":6,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/posts\/2088\/revisions"}],"predecessor-version":[{"id":2109,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/posts\/2088\/revisions\/2109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/media\/2106"}],"wp:attachment":[{"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/media?parent=2088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/categories?post=2088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/tags?post=2088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}