{"id":2080,"date":"2022-09-12T12:12:00","date_gmt":"2022-09-12T15:12:00","guid":{"rendered":"https:\/\/acuinor.cl\/?p=2080"},"modified":"2026-05-08T14:55:35","modified_gmt":"2026-05-08T18:55:35","slug":"produccion-de-seriola-en-caldera-se-abre-paso-en-la-industria-exportadora-de-atacama","status":"publish","type":"post","link":"https:\/\/acuinor.cl\/en\/produccion-de-seriola-en-caldera-se-abre-paso-en-la-industria-exportadora-de-atacama\/","title":{"rendered":"Producci\u00f3n de seriola en Caldera se abre paso en la industria exportadora de Atacama"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2080\" class=\"elementor elementor-2080\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab378bc e-flex e-con-boxed e-con e-parent\" data-id=\"2ab378bc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25622ce9 e-con-full e-flex e-con e-child\" data-id=\"25622ce9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b26aacf elementor-widget elementor-widget-image\" data-id=\"1b26aacf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"727\" height=\"675\" src=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2022\/09\/Captura-de-Pantalla-2026-05-08-a-las-14.53.52.png\" class=\"attachment-full size-full wp-image-2110\" alt=\"\" srcset=\"https:\/\/acuinor.cl\/wp-content\/uploads\/2022\/09\/Captura-de-Pantalla-2026-05-08-a-las-14.53.52.png 727w, https:\/\/acuinor.cl\/wp-content\/uploads\/2022\/09\/Captura-de-Pantalla-2026-05-08-a-las-14.53.52-300x279.png 300w, https:\/\/acuinor.cl\/wp-content\/uploads\/2022\/09\/Captura-de-Pantalla-2026-05-08-a-las-14.53.52-13x12.png 13w\" sizes=\"(max-width: 727px) 100vw, 727px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52de245e e-flex e-con-boxed e-con e-parent\" data-id=\"52de245e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8d1a64 elementor-widget elementor-widget-text-editor\" data-id=\"d8d1a64\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\"><time>Sep 12, 2022<\/time><\/span><\/p><p>La empresa Acuinor inform\u00f3 que a partir de marzo comenzaron los primeros env\u00edos internacionales a los mercados de Estados Unidos y Europa.<\/p><p>Una gran noticia para la oferta exportadora regional entreg\u00f3 la empresa Acu\u00edcola del Norte S.A. Acuicnor, con el inicio de los primeros env\u00edos internacionales de su producto \u201c<em>Seriola lalandi\u201d.<\/em>Desde la zona m\u00e1s des\u00e9rtica del mundo y con m\u00e1s de 15 a\u00f1os de cultivo de esta especie conocida tambi\u00e9n como <em>yellowtail<\/em>, hiramasa, palometa o vidriola, en la empresa han obtenido importantes avances tanto en materia t\u00e9cnica como gen\u00e9tica, a lo que hoy se suma la parte comercial. As\u00ed lo confirm\u00f3 la gerente comercial y de proyectos de Acuinor, Muriel Teixid\u00f3.<\/p><p>\u201cEstamos contentos pues la producci\u00f3n de seriola chilena ya comenz\u00f3, y con ello, el surgimiento de una nueva industria en Atacama. Hoy las nuevas instalaciones de engorda, ya finalizadas, se encuentran en operaci\u00f3n y funcionamiento y han comenzado las cosechas semanales que est\u00e1n siendo exportadas a dos clientes, uno en Europa y otro en Estados Unidos\u201d, indic\u00f3.<\/p><p>Si bien los vol\u00famenes exportados a partir de marzo alcanzan los 400 kilos a la semana, se espera poder ir aument\u00e1ndolos paulatinamente hasta alcanzar cosechas semanales que bordear\u00edan las 3,6 toneladas. As\u00ed mismo, el peso promedio actual de cosecha de 3 kilos, ir\u00e1 progresivamente en aumento hasta alcanzar los 5 kilos como peso promedio de cosecha.<\/p><p>Respecto a la b\u00fasqueda de mercados y clientes, Teixid\u00f3 explic\u00f3 que el mercado siempre ha sido un tema primordial para Acuinor, tanto as\u00ed que con apoyo de programas Corfo se desarrollaron cuatro estudios de mercado \u2013 Estados Unidos, Brasil, Asia y Europa \u2013 donde se contactaron potenciales clientes, se enviaron muestras, se realizaron algunos <em>focus group<\/em> y se obtuvo importante retroalimentaci\u00f3n.<\/p><p>\u201cNos hemos preocupado permanentemente de participar de misiones comerciales, y asistir a las principales ferias y encuentros del sector, y as\u00ed poder estar presentes en los mercados de inter\u00e9s para entablar relaciones comerciales, hacer los contactos y obtener informaci\u00f3n actualizada de mercado de primera fuente. En todo esto, ProChile ha jugado un importante rol al apoyar parte de estas actividades\u201d, se\u00f1al\u00f3.<\/p><p>Justamente, desde la Oficina Regional de ProChile, su directora Claudia Pradenas, destac\u00f3 \u201cel importante apoyo y trabajo que se viene desarrollando con Acuinor, empresa que actualmente cumple su segundo a\u00f1o en el programa de aceleraci\u00f3n comercial ProChile a Tu Medida, bajo el cual se ha avanzado en la exploraci\u00f3n de nuevos mercados de inter\u00e9s y en la consolidaci\u00f3n de los ya existentes. Adem\u00e1s, tambi\u00e9n han sido parte de actividades comerciales en el plano internacional, como la reciente Semana de Atacama en Panam\u00e1, instancia de activaci\u00f3n comercial donde junto a una delegaci\u00f3n de empresas regionales prospectaron las oportunidades del mercado de Centroam\u00e9rica\u201d.<\/p><p>Pradenas tambi\u00e9n valor\u00f3 el aporte en materia laboral y social de la empresa \u2013 que mantiene cerca de 30 trabajadores y cuenta con un convenio de pr\u00e1cticas con el Liceo Manuel Blanco Encalada de Caldera-, adelantando que en las pr\u00f3ximas semanas se concretar\u00e1 una nueva misi\u00f3n comercial a Estados Unidos, buscando reforzar la relaci\u00f3n comercial de Acuinor con sus actuales clientes de la costa este.<\/p><p><strong>El futuro de la <em>Seriola lalandi<\/em><\/strong><\/p><p>Si bien el mercado de la <em>Seriola lalandi<\/em> a\u00fan es incipiente, el producto es conocido y con muy buena aceptaci\u00f3n internacional, contando con un gran potencial de desarrollo por las caracter\u00edsticas del pez, su carne blanca, textura firme, su versatilidad en la cocina. Adem\u00e1s, es altamente apreciado por chefs por sus caracter\u00edsticas culinarias, por sus propiedades nutricionales, alto contenido de prote\u00ednas y omega 3.<\/p><p>Referente a temas log\u00edsticos, desde Acuinor sa\u00f1alaron que en los primeros meses de exportaciones no han tenido inconvenientes, pues la carga fresca sale v\u00eda a\u00e9rea desde Copiap\u00f3 a Santiago y luego contin\u00faa con el tramo internacional hasta destino, contando con oferta diaria de vuelos. En cuanto a la demanda, Teixid\u00f3 indic\u00f3 que ha aumentado debido principalmente por una limitada oferta de seriolas, por la reactivaci\u00f3n del food service y tambi\u00e9n por un aumento del consumo de esta especie.<\/p><p>Apuntando a los mercados de inter\u00e9s, hoy el primer foco est\u00e1 en Estados Unidos y Europa, ambos mercados con una alta y creciente demanda, y es precisamente donde se est\u00e1 exportando desde fines de marzo. \u201cEn la medida que el volumen de cosechas semanales aumente, podremos atender a nuevos clientes y sumar nuevos mercados como Brasil, donde existe un potencial tremendo. China tambi\u00e9n ha estado en nuestra mira y lo estamos prospectando a trav\u00e9s de algunas actividades con ProChile, sin embargo, sabemos que requerir\u00e1 de mayor volumen que a\u00fan no tenemos disponible\u201d, se\u00f1al\u00f3 Teixid\u00f3.<\/p><p>Referente a las pr\u00f3ximas etapas para la producci\u00f3n de la <em>Seriola lalandi<\/em>, Teixid\u00f3 a\u00f1adi\u00f3 que lo que viene es escalar la producci\u00f3n a nivel de empresa para alcanzar vol\u00famenes rentables que logren competitividad y crecimiento.<\/p><p><em><strong>Fotograf\u00edas: Acuinor y ProChile.<\/strong><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Sep 12, 2022 La empresa Acuinor inform\u00f3 que a partir de marzo comenzaron los primeros env\u00edos internacionales a los mercados de Estados Unidos y Europa. Una gran noticia para la oferta exportadora regional entreg\u00f3 la empresa Acu\u00edcola del Norte S.A. Acuicnor, con el inicio de los primeros env\u00edos internacionales de su producto \u201cSeriola lalandi\u201d.Desde la [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notas-de-prensa"],"_links":{"self":[{"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/posts\/2080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/comments?post=2080"}],"version-history":[{"count":7,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/posts\/2080\/revisions"}],"predecessor-version":[{"id":2113,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/posts\/2080\/revisions\/2113"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/media\/2110"}],"wp:attachment":[{"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/media?parent=2080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/categories?post=2080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acuinor.cl\/en\/wp-json\/wp\/v2\/tags?post=2080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}